{"id":7353,"date":"2023-05-11T16:21:53","date_gmt":"2023-05-11T16:21:53","guid":{"rendered":"https:\/\/www.triumph.com\/corporate\/?post_type=careers&#038;p=7353"},"modified":"2023-07-14T15:30:25","modified_gmt":"2023-07-14T15:30:25","slug":"assistente-de-vendas-arrabida-shopping","status":"publish","type":"careers","link":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/","title":{"rendered":"Assistente de vendas &#8211; Arr\u00e1bida Shopping"},"content":{"rendered":"","protected":false},"featured_media":0,"menu_order":108,"template":"","locations":[1790,27],"career_types":[72],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assistente de vendas - Arr\u00e1bida Shopping - Triumph<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistente de vendas - Arr\u00e1bida Shopping - Triumph\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/\" \/>\n<meta property=\"og:site_name\" content=\"Triumph\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T15:30:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/\",\"url\":\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/\",\"name\":\"Assistente de vendas - Arr\u00e1bida Shopping - Triumph\",\"isPartOf\":{\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/#website\"},\"datePublished\":\"2023-05-11T16:21:53+00:00\",\"dateModified\":\"2023-07-14T15:30:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.triumph.com\/corporate\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OUR CAREERS \u2013 JOBS LIST\",\"item\":\"https:\/\/www.triumph.com\/corporate\/es\/careers\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assistente de vendas &#8211; Arr\u00e1bida Shopping\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/#website\",\"url\":\"https:\/\/www.triumph.com\/corporate\/es\/\",\"name\":\"Triumph\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.triumph.com\/corporate\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/#organization\",\"name\":\"Triumph\",\"url\":\"https:\/\/www.triumph.com\/corporate\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.triumph.com\/corporate\/wp-content\/uploads\/2022\/06\/favicon.png\",\"contentUrl\":\"https:\/\/www.triumph.com\/corporate\/wp-content\/uploads\/2022\/06\/favicon.png\",\"width\":48,\"height\":44,\"caption\":\"Triumph\"},\"image\":{\"@id\":\"https:\/\/www.triumph.com\/corporate\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistente de vendas - Arr\u00e1bida Shopping - Triumph","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/","og_locale":"es_ES","og_type":"article","og_title":"Assistente de vendas - Arr\u00e1bida Shopping - Triumph","og_url":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/","og_site_name":"Triumph","article_modified_time":"2023-07-14T15:30:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/","url":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/","name":"Assistente de vendas - Arr\u00e1bida Shopping - Triumph","isPartOf":{"@id":"https:\/\/www.triumph.com\/corporate\/es\/#website"},"datePublished":"2023-05-11T16:21:53+00:00","dateModified":"2023-07-14T15:30:25+00:00","breadcrumb":{"@id":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.triumph.com\/corporate\/es\/careers\/assistente-de-vendas-arrabida-shopping\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.triumph.com\/corporate\/es\/"},{"@type":"ListItem","position":2,"name":"OUR CAREERS \u2013 JOBS LIST","item":"https:\/\/www.triumph.com\/corporate\/es\/careers\/"},{"@type":"ListItem","position":3,"name":"Assistente de vendas &#8211; Arr\u00e1bida Shopping"}]},{"@type":"WebSite","@id":"https:\/\/www.triumph.com\/corporate\/es\/#website","url":"https:\/\/www.triumph.com\/corporate\/es\/","name":"Triumph","description":"","publisher":{"@id":"https:\/\/www.triumph.com\/corporate\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.triumph.com\/corporate\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.triumph.com\/corporate\/es\/#organization","name":"Triumph","url":"https:\/\/www.triumph.com\/corporate\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.triumph.com\/corporate\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.triumph.com\/corporate\/wp-content\/uploads\/2022\/06\/favicon.png","contentUrl":"https:\/\/www.triumph.com\/corporate\/wp-content\/uploads\/2022\/06\/favicon.png","width":48,"height":44,"caption":"Triumph"},"image":{"@id":"https:\/\/www.triumph.com\/corporate\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/careers\/7353"}],"collection":[{"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/careers"}],"about":[{"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/types\/careers"}],"version-history":[{"count":2,"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/careers\/7353\/revisions"}],"predecessor-version":[{"id":7371,"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/careers\/7353\/revisions\/7371"}],"wp:attachment":[{"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/media?parent=7353"}],"wp:term":[{"taxonomy":"locations","embeddable":true,"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/locations?post=7353"},{"taxonomy":"career_types","embeddable":true,"href":"https:\/\/www.triumph.com\/corporate\/es\/wp-json\/wp\/v2\/career_types?post=7353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}